{"id":10495,"date":"2017-12-28T00:04:48","date_gmt":"2017-12-27T23:04:48","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?p=10495"},"modified":"2024-09-11T12:21:54","modified_gmt":"2024-09-11T10:21:54","slug":"3d-gedrucktes-getraenk281220171","status":"publish","type":"post","link":"https:\/\/www.3dnatives.com\/de\/3d-gedrucktes-getraenk281220171\/","title":{"rendered":"Smart Cups-ein 3D-gedrucktes Getr\u00e4nk voller Energie"},"content":{"rendered":"<p style=\"text-align: justify;\">Smart Cups hat Pl\u00e4ne bekannt gegeben, biologisch abbaubare Becher aus Kunststoff auf den Markt zu bringen, welche gleichzeitig einen Energy Drink erzeugen. Aber was genau ist ein\u00a03D-gedrucktes Getr\u00e4nk?<\/p>\n<p style=\"text-align: justify;\">Das in Kalifornien ans\u00e4ssige Startup Smart Cups hat mit seinem neuesten Produkt Etwas kreiert, was bisher in dieser Form noch nicht auf dem Markt zu finden ist. Sie verkaufen diese nachhaltigen Becher, aber wenn Sie Wasser in diese einf\u00fcllen, entstehen in den Bechern laut Herstellerangaben leckere Energy Drinks. Dies funktioniert in der Weise, dass auf dem Boden des Bechers 3D-gedruckte Kapseln zu finden sind, die sich bei Kontakt mit Wasser aufl\u00f6sen und auf diese Art und Weise das Wasser geschmacklich ver\u00e4ndern. Das Unternehmen plant f\u00fcr das 3D-gedruckte Getr\u00e4nk vier verschiedene Geschmacksrichtungen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10502 aligncenter\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Smart-Cups-2.jpg\" alt=\"3D-gedrucktes Getr\u00e4nk\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Smart-Cups-2.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Smart-Cups-2-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Smart-Cups-2-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/Smart-Cups-2-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3>Der Hintergrund zum 3D-gedruckten Getr\u00e4nk<\/h3>\n<p style=\"text-align: justify;\">Die urspr\u00fcngliche Idee stammt von Chris Kanik zusammen mit The Additiv Advantage, haben Smart Cups die Plastikbecherindustrie revolutioniert. Diese Tassen sind nicht nur biologisch abbaubar, sondern bieten eine Reihe weiterer Vorteile gegen\u00fcber herk\u00f6mmlichen Energydrinks. Sobald Wasser hinzugef\u00fcgt wurde, vermischt sich die 3D-gedruckte Schicht am Boden mit dem Wasser und aromatisiert das Wasser, um das beworbene Erfrischungsgetr\u00e4nk herzustellen.<\/p><div class=\"dnati-inside-article dnati-entity-placement\" id=\"dnati-549175160\"><div id=\"dnati-657664267\"><a data-no-instant=\"1\" href=\"https:\/\/npe.org\/become-an-exhibitor\/?utm_campaign=9317304-NPE2027%20Exhibitor%20Prospect%20Communications&#038;utm_source=3Dnatives&#038;utm_medium=banner%20ad&#038;utm_term=apply%20today_3D\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"NPE2027_Feathr Ads_850x150 (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png\" alt=\"\"  srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1.png 850w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-600x106.png 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-768x136.png 768w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/NPE2027_Feathr-Ads_850x150-1-160x28.png 160w\" sizes=\"(max-width: 850px) 100vw, 850px\" width=\"850\" height=\"150\"   \/><\/a><\/div><\/div>\n<p style=\"text-align: justify;\">Diese Kapseln werden normalerweise in der Medizin beispielsweise f\u00fcr Medikamente eingesetzt und mithilfe additiver Herstellungsverfahren hergestellt. In der l\u00f6slichen Polymerh\u00fclle sind verschiedene Materialien integriert, die bei Kontakt mit Wasser freigesetzt werden. Deren Katalyxt-Schicht verwandeln das Wasser in den gew\u00fcnschten Energy Drink.<\/p>\n<p style=\"text-align: justify;\">Smart Cups hat bislang vier verschiedene Energydrinks 3D-gedruckt und bietet folgende Geschmacksrichtungen an: Pucker Up Brain Boost, Tropical Recess, Magna Cum Latte und Nerdy Lemon-T. Wenn dies Erfolg hat, k\u00f6nnten wir in Zukunft vielleicht eine 3D-gedruckte Cola genie\u00dfen.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_10505\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10505\" class=\"wp-image-10505 size-full\" src=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/smart-cups-3.jpg\" alt=\"3D-gedrucktes Getr\u00e4nk\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/smart-cups-3.jpg 700w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/smart-cups-3-600x343.jpg 600w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/smart-cups-3-160x91.jpg 160w, https:\/\/www.3dnatives.com\/de\/wp-content\/uploads\/sites\/3\/smart-cups-3-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-10505\" class=\"wp-caption-text\">Ein \u00dcberblick \u00fcber die vier verschiedenen Geschmacksrichtungen.<\/p><\/div>\n<h3>Eine neue Art des Konsums?<\/h3>\n<p style=\"text-align: justify;\">Dieses Projekt l\u00e4sst uns fragen, ob wir in Zukunft auf diese Art und Weise, Essen zu Trinken konsumieren werden. Ob sich dieses Produkt auf dem Markt durchsetzen wird, wird sich zeigen, aber interessant ist es allemal, wenn man beispielsweise bedenkt, was dies f\u00fcr Astronauten bedeuten k\u00f6nnte.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/KvlVdsXcHcM?si=1Fh7_YbEaiZ0hdCB\" width=\"700\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h3>Was halten Sie pers\u00f6nlich von diesem 3D-gedruckten Getr\u00e4nk?<\/h3>\n<p style=\"text-align: justify;\">Weitere Informationen zu diesem Thema erhalten Sie auf der <a href=\"https:\/\/smartcups.com\/\">Webseite<\/a> von Smart Cups.<\/p>\n<p style=\"text-align: justify;\">M\u00f6chten Sie eine Zusammenfassung der wichtigsten Neuigkeiten im 3D-Druck und der additiven Fertigung direkt und bequem in Ihr Postfach? Registrieren Sie sich jetzt f\u00fcr unseren <a href=\"https:\/\/www.3dnatives.com\/de\/3d-druck-newsletter\/\">w\u00f6chentlichen Newsletter<\/a> und folgen Sie uns auf <a href=\"https:\/\/www.facebook.com\/3Dnativesde\/\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/?lang=en\">Twitter <\/a>und <a href=\"https:\/\/plus.google.com\/b\/110137870176740423201\/\">Google+<\/a>, um stets auf dem Laufenden zu bleiben! Au\u00dferdem sind wir auch auf <a href=\"https:\/\/www.xing.com\/communities\/groups\/3d-druck-und-additive-fertigung-c15a-1091770\">XING <\/a>und <a href=\"https:\/\/www.linkedin.com\/groups\/13502336\">LinkedIN<\/a> zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Smart Cups hat Pl\u00e4ne bekannt gegeben, biologisch abbaubare Becher aus Kunststoff auf den Markt zu bringen, welche gleichzeitig einen Energy Drink erzeugen. Aber was genau ist ein\u00a03D-gedrucktes Getr\u00e4nk? Das in Kalifornien ans\u00e4ssige Startup Smart Cups hat mit seinem neuesten Produkt&hellip;<\/p>\n","protected":false},"author":6052,"featured_media":10498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-10495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/10495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/users\/6052"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/comments?post=10495"}],"version-history":[{"count":3,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/10495\/revisions"}],"predecessor-version":[{"id":58697,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/posts\/10495\/revisions\/58697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/10498"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=10495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/categories?post=10495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/tags?post=10495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}