{"id":38694,"date":"2022-06-27T11:17:57","date_gmt":"2022-06-27T09:17:57","guid":{"rendered":"https:\/\/www.3dnatives.com\/de\/?post_type=ntv_events&#038;p=38694"},"modified":"2022-06-27T11:20:11","modified_gmt":"2022-06-27T09:20:11","slug":"3dkonzeptlabs-2022","status":"publish","type":"ntv_events","link":"https:\/\/www.3dnatives.com\/de\/veranstaltungen\/3dkonzeptlabs-2022\/","title":{"rendered":"3DKonzeptLabs 2022"},"content":{"rendered":"<p>Bei den 3DKonzeptLabs 2022 dreht sich alles um dem 3D-Druck \u201eauf dem Bau\u201c \u2013 Materialien, Anwendungsbeispiele, Trends und und und. Plus ein Blick \u00fcber den Tellerrand \u2013 auf einen 3D-Druck-Prozess \u201eon demand\u201c.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Donnerstag, 30. Juni 2022 \u2013 ab 17:00 Uhr\u00a0<\/strong><\/h2>\n<p style=\"text-align: justify;\">Netzwerkabend im Freien \u2013 Sie sind herzlich eingeladen! Wir freuen uns, Sie in lockerer Atmosph\u00e4re zu einem Getr\u00e4nk und kleinem Imbiss zu treffen.<\/p>\n<p style=\"text-align: justify;\">Wegen begrenzter Personenzahl ist eine\u00a0<a href=\"mailto:bi**********@************ck.berlin\" data-original-string=\"BVUmM2P2oGAVpu23i1gdKQ==58doPQ+CIQEWdEEd6x5b4WEECI1z018x6oWB7QksX5DsagRKY39tBpScxGlbxhSjf4H\" title=\"Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.\" target=\"_blank\" rel=\"noopener\">Anmeldung<\/a>\u00a0unbedingt notwendig!<\/p>\n<h2><strong>Freitag, 1. Juli2022 \u2013 9:00 bis 14:00 Uhr<\/strong><\/h2>\n<p>Digitale Konferenz zum Thema 3D-Druck am Bau. Nach Ihrer\u00a0<a href=\"mailto:bi**********@************ck.berlin\" data-original-string=\"dY7fY+JwdDJjYw9MPd\/ogQ==58dNk7Asel+FKyW3DVU0U2WTQfqPX24T6R8Vp2gMFog+Cyo9qYZVIddNNknYtD1wBVe\" title=\"Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.\" target=\"_blank\" rel=\"noopener\">Anmeldung<\/a> werden Ihnen die Zugangsdaten zugesendet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei den 3DKonzeptLabs 2022 dreht sich alles um dem 3D-Druck \u201eauf dem Bau\u201c \u2013 Materialien, Anwendungsbeispiele, Trends und und und. Plus ein Blick \u00fcber den Tellerrand \u2013 auf einen 3D-Druck-Prozess \u201eon demand\u201c. &nbsp; Donnerstag, 30. Juni 2022 \u2013 ab 17:00&hellip;<\/p>\n","protected":false},"featured_media":38695,"template":"","ntv_event_cat":[],"ntv_organizer":[103],"class_list":["post-38694","ntv_events","type-ntv_events","status-publish","has-post-thumbnail","hentry","ntv_organizer-verband-3ddruck-e-v"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/ntv_events\/38694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/ntv_events"}],"about":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/types\/ntv_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media\/38695"}],"wp:attachment":[{"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/media?parent=38694"}],"wp:term":[{"taxonomy":"ntv_event_cat","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/ntv_event_cat?post=38694"},{"taxonomy":"ntv_organizer","embeddable":true,"href":"https:\/\/www.3dnatives.com\/de\/wp-json\/wp\/v2\/ntv_organizer?post=38694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}